{"id":5684,"date":"2022-12-25T14:25:12","date_gmt":"2022-12-25T14:25:12","guid":{"rendered":"https:\/\/laprimicianoticias.com\/?p=5684"},"modified":"2022-12-25T14:25:14","modified_gmt":"2022-12-25T14:25:14","slug":"llena-eres-de-gracia","status":"publish","type":"post","link":"https:\/\/laprimicianoticias.com\/index.php\/2022\/12\/25\/llena-eres-de-gracia\/","title":{"rendered":"Llena eres de gracia"},"content":{"rendered":"\n<p>Por: Larry Caballero <\/p>\n\n\n\n<p>17 de agosto 1958,&nbsp; Chevrolet impala, modelo 56, color rojo, techo r\u00edgido, despu\u00e9s de un fin de semana de playa y sol, regresaba la familia Rodr\u00edguez a su casa, padre, madre y la peque\u00f1a Mar\u00eda Cristina de 8 a\u00f1os. Mar\u00eda Cristina se divert\u00eda viendo las luces a la distancia de la ciudad que se alejaban, la mam\u00e1 y pap\u00e1 conversaban sobre la familia Villalobos, quienes por casualidad se los hab\u00edan encontrado en varias ocasiones por el hotel, de fondo sonaba una canci\u00f3n de Alci Acosta, que hac\u00eda del viaje de regreso, por lo pronto placentero.<\/p>\n\n\n\n<p>-De tantos hoteles, ten\u00edamos que hospedarnos donde estaban los Villalobos &#8211; dijo el pap\u00e1 con voz de gente amargada.&nbsp;<\/p>\n\n\n\n<p>-Bueno no te amargues m\u00e1s con eso, ya pas\u00f3.<\/p>\n\n\n\n<p>-Es que me da bronca, se creen superiores y Carlos me aburre con sus temas pol\u00edticos conservadores.<\/p>\n\n\n\n<p>-Bueno ni hablar, ya te dije que no te amargues con ese tema, te gusta darle y darle, siempre es lo mismo.<\/p>\n\n\n\n<p>-\u00a1Bueno \u00bfpero t\u00fa de qu\u00e9 lado est\u00e1s?!&nbsp;<\/p>\n\n\n\n<p>La mam\u00e1 hizo silencio, solo ve\u00eda por la ventana del carro esperando que Pap\u00e1 callara, se hac\u00eda la dormida, pero eso enfurec\u00eda m\u00e1s al pap\u00e1.<\/p>\n\n\n\n<p>-No me est\u00e9s ignorando, ahora t\u00fa te crees mejor que yo.<\/p>\n\n\n\n<p>-Creo que a\u00fan tienes tragos en la cabeza, por favor mira que la ni\u00f1a est\u00e1 escuchando.<\/p>\n\n\n\n<p>&#8211; Si, tengo trago \u00bfy qu\u00e9?, pero tengo raz\u00f3n, parece que todos est\u00e1n en mi contra.<\/p>\n\n\n\n<p>-\u00a1Pap\u00e1! mira como se ve la luna, est\u00e1 cortada por la mitad.<\/p>\n\n\n\n<p>-Ahora no hija , ahora no.<\/p>\n\n\n\n<p>-\u00a1Rosalba m\u00edrame cuando te hablo!<\/p>\n\n\n\n<p>-Tengo sue\u00f1o, quiero dormir, estoy cansada.<\/p>\n\n\n\n<p>&#8211; Pap\u00e1, \u00bfporqu\u00e9 la luna se ve tapada?<\/p>\n\n\n\n<p>-Hija du\u00e9rmete, a\u00fan falta mucho para llegar.<\/p>\n\n\n\n<p>La estaci\u00f3n de radio anunciaba la hora, 8:40 PM,&nbsp; parece que se aproxima una&nbsp; &nbsp;fuerte lluvia, los dejamos&nbsp; con&nbsp; Lucho Berm\u00fadez y su \u00e9xito \u00a1prende la vela!.<\/p>\n\n\n\n<p>&#8211; Mam\u00e1 tengo hambre.<\/p>\n\n\n\n<p>&#8211; Mi amor haz caso a tu pap\u00e1, duerme.<\/p>\n\n\n\n<p>&#8211; Soy yo quien lleva el peso de la familia &#8211; dec\u00eda el pap\u00e1 con ganas de seguir discutiendo. &#8211; Todo es por mi, tu te la pasas cotorreando con tus amigas, no sabes ni cocinar bien.<\/p>\n\n\n\n<p>La mam\u00e1 segu\u00eda en silencio viendo por la ventana.<\/p>\n\n\n\n<p>&#8211; Te he dicho que me mires cuando hablo.<\/p>\n\n\n\n<p>La lluvia empez\u00f3 a caer, el pap\u00e1 segu\u00eda hablando y renegando por todo, la mam\u00e1 se ve\u00eda cansada, rogando llegar r\u00e1pido a la casa. A Mar\u00eda Cristina le gustaba el olor a cuero de los asientos y las gotas de lluvia pegando en el vidrio de su ventana.<\/p>\n\n\n\n<p>&#8211; Lo que faltaba maldita lluvia, todo es una mierda.- dijo Pap\u00e1 golpeando el volante.<\/p>\n\n\n\n<p>&#8211; \u00a1Yaa! Hijo de puta, estoy harta de ti, de tu est\u00fapida quejadera, eres un pedazo de mierda, un fracasado, con un empleo de mierda, \u00a1Hijo de puta!<\/p>\n\n\n\n<p>El pap\u00e1 conect\u00f3 una cachetada con su mano derecha, volte\u00e1ndole la cara a&nbsp; la mam\u00e1, el carro hace un Zig zag, el pap\u00e1 trato de controlarlo, unas l\u00e1mparas le encandilaron los ojos, el pap\u00e1 trato de esquivar ese cami\u00f3n, el carro sale de la carretera, el pap\u00e1 pisa el freno pero nada lo detiene, solo un \u00e1rbol de ca\u00f1aguate firme, que ni se estremeci\u00f3 con el golpe, fue un golpe seco, la mam\u00e1 sali\u00f3 volando por el parabrisas, el pap\u00e1 qued\u00f3 atrapado entre el volante, las latas del carro y el \u00e1rbol, ten\u00eda solo media cara, la otra media sangre y sesos se perdieron entre las latas, la mam\u00e1 quedo a unos 30 metros, sus piernas estaban como al rev\u00e9s, un hueco profundo en la frente se alcanza a ver a la distancia, Mar\u00eda Cristina ten\u00eda puesto su cintur\u00f3n que ella misma se lo coloc\u00f3, un vidrio cort\u00f3 su cara, fue el \u00fanico da\u00f1o que sufri\u00f3, la lluvia era m\u00e1s fuerte, en pocos minutos lleg\u00f3 la ambulancia y la polic\u00eda. Sentada en la ambulancia, Mar\u00eda Cristina solo ve\u00eda dos bolsa negras que eran cargadas en una camilla hacia otra ambulancia, la lluvia ces\u00f3, Mar\u00eda Cristina miraba al cielo, ya no hab\u00eda luna y el canto de las ranas eran melod\u00edas para sus o\u00eddos.<\/p>\n\n\n\n<p>2&nbsp;<\/p>\n\n\n\n<p>Mar\u00eda Cristina fue llevada al hospital infantil la casa del ni\u00f1o, ten\u00eda una cortada en su mejilla izquierda que le iba dejar una gran cicatriz, afortunadamente no tuvo fracturas ni traumas graves. Carmenza, hermana de su pap\u00e1, era quien se har\u00eda cargo de Mar\u00eda Cristina. Firm\u00f3 unos papeles y le dieron de alta, la llev\u00f3 a su casa, Carmenza era madre soltera, ten\u00eda un ni\u00f1o con retraso mental, quien era cuidado por una se\u00f1ora especialista en esos casos, Carmenza trabajaba en un gran almac\u00e9n de telas y siempre llegaba tarde a casa. El sepelio fue a los dos d\u00edas, unos cuantos vecinos, los Villalobos y los profesores de la escuela de Mar\u00eda Cristina fueron los que asistieron.<\/p>\n\n\n\n<p>Unas semanas despu\u00e9s, Carmenza firm\u00f3 otro papeles, eran los papeles de la custodia de Mar\u00eda Cristina, Carmenza no estaba muy alegre, era otra carga, pero no hab\u00eda m\u00e1s familiares que pudieran hacerse cargo de Mar\u00eda Cristina, no hab\u00eda herencia, no hab\u00eda nada, ni casa, ni carro, nada. El padre de Mar\u00eda Cristina era un mediocre que no hizo riqueza, siempre viv\u00edan con deudas y arrendados. Pocos d\u00edas despu\u00e9s, Mar\u00eda Cristina regresa a la escuela, era sometida a burlas por su cicatriz y las que eran sus amiguitas ya le ve\u00edan rara, Mar\u00eda Cristina se qued\u00f3 sola, nadie se sentaba a su lado a comer, ella aborrec\u00eda a los ni\u00f1os, eran los m\u00e1s pesados con ella. Los d\u00edas en la escuela eran un infierno, Mar\u00eda Cristina comenz\u00f3 a tener pensamientos oscuros, se imaginaba d\u00e1ndole cuchillazos en el est\u00f3mago a los ni\u00f1os que la molestaban, ten\u00eda pesadillas con el d\u00eda del accidente, ve\u00eda la cara de su pap\u00e1 llena de sangre y peleando con su mam\u00e1, so\u00f1aba que su mam\u00e1 la abrazaba y despu\u00e9s la tiraba por un precipicio. Una ma\u00f1ana Mar\u00eda Cristina estaba comiendo su merienda, sola como siempre, y tres ni\u00f1os se le acercaron, tomaron su yogurt y unas empanadas que le hab\u00eda hecho la se\u00f1ora que cuidaba a su primo.&nbsp;<\/p>\n\n\n\n<p>&#8211; Hola cara cortada, hoy quiero tu merienda, se ven ricas esas empanadas.<\/p>\n\n\n\n<p>&#8211; M\u00e1s te vale que me las devuelvas.&nbsp;<\/p>\n\n\n\n<p>&#8211; \u00bfO que vas hacer?, mira como tiemblo<\/p>\n\n\n\n<p>&#8211; Dame mis empanadas.<\/p>\n\n\n\n<p>&#8211; \u00bfLas quieres?, \u00a1Pues t\u00f3malas!<\/p>\n\n\n\n<p>El ni\u00f1o las tir\u00f3 a un charco que estaba cerca, los otros ni\u00f1os se re\u00edan y le dec\u00edan \u201c\u00a1Cara cortada! \u00a1Cara cortada!\u201d<\/p>\n\n\n\n<p>Mar\u00eda Cristina toma un l\u00e1piz que reci\u00e9n le hab\u00eda sacado la punta, se lanz\u00f3 contra el ni\u00f1o y le incrust\u00f3 el l\u00e1piz en el ojo izquierdo, luego lo empuj\u00f3 lo tiro al suelo y le dijo:<\/p>\n\n\n\n<p>&#8211; Te dije que me devolvieras mis empanadas.<\/p>\n\n\n\n<p>Los otros ni\u00f1os salieron corriendo, una profesora que pasaba di\u00f3 un grito que se escuch\u00f3 en toda la escuela \u201c\u00a1DIOS SANTO QUE HAS HECHO!\u201d<\/p>\n\n\n\n<p>Mar\u00eda Cristina ten\u00eda que ir semanalmente a sesiones de psicoterapia, ya que dec\u00edan que era una ni\u00f1a traumatizada, pero otros dec\u00edan que estaba pose\u00edda por el mismo demonio.<\/p>\n\n\n\n<p>3<\/p>\n\n\n\n<p>La habitaci\u00f3n de una adolescente, afiches de los Beatles, fotos pegadas, ropa tirada, zapatos regados, hab\u00edan pasado 7 a\u00f1os despu\u00e9s de lo ocurrido, sin escuela, sin ley, pelo enmara\u00f1ado, casi siempre ropa negra puesta, 1.60 de estatura, senos peque\u00f1o pero firmes, culo redondo, piernas gruesas, la cicatriz la hac\u00eda ver mas sexi, Mar\u00eda Cristina hizo metamorfosis, dejo el capullo tirado y se convirti\u00f3 en una mariposa oscura, bella, pero venenosa. Su t\u00eda Carmenza se hab\u00eda quedado sin trabajo hace un par de a\u00f1os, viv\u00eda de un subsidio que le daba el gobierno por su hijo especial, el ni\u00f1o ya ten\u00eda 11 a\u00f1os, a&nbsp; Mar\u00eda Cristina le parec\u00eda repugnante, estaba gordo, en silla de ruedas y se cagaba los pantalones, la pobre Carmenza ya no pod\u00eda pagar para que lo cuidaran, ten\u00eda todo ese peso, hab\u00eda d\u00edas que&nbsp; no ten\u00eda&nbsp; fuerzas y maldec\u00eda su vida, la casa se deterioraba, le hac\u00eda falta pintura y el frente se llenaba de monte, sin embargo se las arreglaba para sobrevivir d\u00eda a d\u00eda. Mar\u00eda Cristina siempre estaba en su cuarto, escuchando m\u00fasica con una vieja radio que solo sintonizaba una sola emisora, no ten\u00eda amigos, cuando lograba tener contacto con alguien al poco tiempo se alejaban de ella. Un d\u00eda escucho unas risas juguetonas al lado de la casa, se asom\u00f3 por la ventana, era una ma\u00f1ana hermosa, un sol c\u00e1lido, como los soles de verano, con algo de brisa,&nbsp; hab\u00edan dos lindas&nbsp; j\u00f3venes arroj\u00e1ndose agua con una manguera, ten\u00edan puesto vestido de ba\u00f1o, el agua hac\u00eda que los picos de los senos resaltaran, las nalgas se le ve\u00edan firmes y blancas. Mar\u00eda Cristina sinti\u00f3 que sus hormonas efervesc\u00edan, tanto que se retorci\u00f3 con las manos&nbsp; entre pierna, segu\u00eda mirando y se tocaba sus peque\u00f1os senos, se mord\u00eda los labios, se baj\u00f3 el short que ten\u00eda hasta la rodilla junto con su panty, segu\u00eda viendo y como una gata en celo haciendo todo por instinto, comenz\u00f3 a frotar su cl\u00edtoris con sus dedos suaves, el cl\u00edtoris&nbsp; est\u00e1ba m\u00e1s grande de lo normal, su vulva estaba mojada y muy caliente, temblaba como caballo con fr\u00edo, su coraz\u00f3n lat\u00eda 1000 por hora, jam\u00e1s hab\u00eda experimentado esa sensaci\u00f3n, no sab\u00eda que pod\u00eda tener tanto placer viendo esas dos adolescentes y toc\u00e1ndose de esa manera, ella misma se&nbsp; tapa la boca para no gritar, introdujo dos dedos en su vagina caliente, sinti\u00f3 algo de dolor pero el placer era iinfinito. Justo cuando est\u00e1n por desencadenar un orgasmo profundo entr\u00f3 su t\u00eda a la habitaci\u00f3n.<\/p>\n\n\n\n<p>-\u00a1Que haces hija del demonio! \u00a1Enferma!<\/p>\n\n\n\n<p>Carmenza era muy conservadora, tom\u00f3 una escoba para pegarle, Mar\u00eda Cristina r\u00e1pidamente se alz\u00f3 el short, la t\u00eda trat\u00f3 de golpearla pero Mar\u00eda Cristina era m\u00e1s \u00e1gil y se defendi\u00f3 tomando&nbsp; con la mano la escoba.<\/p>\n\n\n\n<p>-\u00a1D\u00e9jeme en paz t\u00eda!, \u00a1Yo ya no soy una ni\u00f1a!<\/p>\n\n\n\n<p>Mar\u00eda Cristina se separa de la t\u00eda con un empuj\u00f3n, la t\u00eda resbala, cae al piso y se da un golpe en la cabeza, queda aturdida pero consiente, Mar\u00eda Cristina entra en ataque de histeria, empieza a gritar y a tirar todo.<\/p>\n\n\n\n<p>-\u00a1Malditos sean todos!, \u00a1Todos deben morirse!, Los voy a matar hijos de puta! Los gritos se escuchan en la calle, Mar\u00eda Cristina tiraba espejos, jarros, todo lo que pod\u00eda, la t\u00eda c\u00f3mo pudo se levant\u00f3 sali\u00f3 casi corriendo y cerr\u00f3 la habitaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>-Dios santo, tiene un demonio, tengo que pedir ayuda.<\/p>\n\n\n\n<p>A los pocos minutos llegaba una ambulancia, dos hombres vestidos de blanco entraron a la habitaci\u00f3n, la agarraron.<\/p>\n\n\n\n<p>-\u00a1Su\u00e9ltenme hijos de puta!, \u00a1su\u00e9ltenme!<\/p>\n\n\n\n<p>Uno de los hombres le coloc\u00f3 una inyecci\u00f3n que la puso a dormir, Mar\u00eda Cristina es llevada a la cl\u00ednica psiqui\u00e1trica. Una luz blanca encandece sus ojos, poco a poco los va abriendo, observa un cuarto muy blanco, tiene una camisa de fuerza puesta, una se\u00f1ora con bata blanca entra a la habitaci\u00f3n.<\/p>\n\n\n\n<p>-Hola Mar\u00eda Cristina, ac\u00e1 est\u00e1s de nuevo, soy la doctora Patricia, te hemos puesto un calmante por eso te debes sentir con algo de mareo.<\/p>\n\n\n\n<p>Mari\u00e1 Cristina trataba de soltarse pero era imposible.&nbsp;<\/p>\n\n\n\n<p>-\u00bfPor qu\u00e9 siempre me traen ac\u00e1?<\/p>\n\n\n\n<p>-Ya lo sabes, ac\u00e1 siempre te traemos despu\u00e9s de tus ataques.<\/p>\n\n\n\n<p>-No quiero estar ac\u00e1, dejenme ir.<\/p>\n\n\n\n<p>-Ya regreso. &#8211; Dijo la doctora&nbsp;<\/p>\n\n\n\n<p>La doctora sali\u00f3, afuera est\u00e1ba la t\u00eda esperando.<\/p>\n\n\n\n<p>-Hola se\u00f1ora Carmenza, vamos a dejar a Mar\u00eda Cristina unos d\u00edas, ya despu\u00e9s puede regresar a su casa, solo es lo de siempre.<\/p>\n\n\n\n<p>-Ya no la soporto, un d\u00eda de esto me va a matar, pienso meterla al convento \u00bfusted qu\u00e9 opina?<\/p>\n\n\n\n<p>-Me parece buena idea, ella necesita disciplina y la ayuda espiritual le servir\u00e1, aseg\u00farese de que tome sus pastillas.<\/p>\n\n\n\n<p>4<\/p>\n\n\n\n<p>A los pocos d\u00edas estaba en la puerta de la casa un carro negro viejo de esos que usan para las funerarias y dos monjas esperando, una era joven, de unos 25 a\u00f1os, la otra si era mayor, como de 45, Mar\u00eda Cristina sal\u00eda de la casa con dos maletas de cuero deste\u00f1idas, su t\u00eda la ve\u00eda por la ventana con cara de alivio, la monja joven le ayuda con las maletas.<\/p>\n\n\n\n<p>-Hola Mar\u00eda Cristina, soy la hermana Sof\u00eda, te llevaremos a tu nuevo hogar.<\/p>\n\n\n\n<p>Mar\u00eda Cristina notaba que la monja mayor la reparaba desde los pies a la cabeza, como si estuviera comprando ganado, Mar\u00eda Cristina subi\u00f3 al carro en el asiento trasero , miraba hacia atr\u00e1s pero sab\u00eda que nadie la iba extra\u00f1ar y que quiz\u00e1s el convento ser\u00eda lo mejor para ella. El convento se llamaba Santa Cruz de la Popa, estaba en un cerro y ten\u00eda una vista bonita, se pod\u00eda ver todo el mar y la ciudad. El carro lleg\u00f3 hasta cierto punto, despu\u00e9s ten\u00edan que ascender caminado por una escalera hecha de piedra. Al llegar hab\u00eda otra monja que las estaba esperando.<\/p>\n\n\n\n<p>-Hola hermana Esther, fue un largo viaje y hace un calor impresionante, \u00bfya tiene lista la habitaci\u00f3n de la joven?<\/p>\n\n\n\n<p>-Si Madre Roberta, ya est\u00e1 lista.<\/p>\n\n\n\n<p>El convento era grande, muy colonial, pero con cierto misterio.<\/p>\n\n\n\n<p>-Le presento a nuestra nueva novicia, Mar\u00eda Cristina Rodr\u00edguez.<\/p>\n\n\n\n<p>&nbsp;-Es un gusto Mar\u00eda Cristina, yo ser\u00e9 tu gu\u00eda, te dar\u00e9 un recorrido y te llevar\u00e9 a tu habitaci\u00f3n.<\/p>\n\n\n\n<p>Mari\u00e1 Cristina se sent\u00eda muy extra\u00f1a, las cosas de Dios no eran lo de ella, hab\u00eda un se\u00f1or reparando una puerta y un joven que era su ayudante, el joven no dejaba de ver a Mar\u00eda Cristina, tanto que ya incomodaba.<\/p>\n\n\n\n<p>Entraron al convento, hab\u00eda un olor a incienso que le provocaba n\u00e1useas.<\/p>\n\n\n\n<p>-Tengo informaci\u00f3n de ti, se por todo lo que has pasado.<\/p>\n\n\n\n<p>-\u00bfInformaci\u00f3n?<\/p>\n\n\n\n<p>-Si, se todo lo que te ha pasado, pero tranquila ac\u00e1 estar\u00e1s bien.- Le dijo la monja tocando su espalda.<\/p>\n\n\n\n<p>El convento era limpio, agradable a la vista, ten\u00eda muchas imagenes y estatuas cat\u00f3licas, por alguna raz\u00f3n Mar\u00eda Cristina sent\u00eda que ya hab\u00eda vivido en ese lugar, ten\u00eda como recuerdos vagos que llegaban a su mente.<\/p>\n\n\n\n<p>-Ac\u00e1 te pondr\u00e1s al d\u00edas con tus clases, tambi\u00e9n har\u00e1s trabajos manuales, hacemos artesan\u00edas, ostias, galletas, con eso el convento se sostiene econ\u00f3micamente ya que lo que nos da el estado no alcanza y cada vez somos m\u00e1s hermanas.<\/p>\n\n\n\n<p>&nbsp;El convento estaba conformado por 1 madre superiora, 2 Madres, 3 Sor, 13 hermanas y 7 novicias incluyendo a Mar\u00eda Cristina, cada 15 d\u00edas ten\u00edan la visita del arzobispado Luis Fernando Ospino y su comitiva.<\/p>\n\n\n\n<p>-Esta es tu habitaci\u00f3n, m\u00e1s tarde te hago llegar tu h\u00e1bito, por ahora descansa. Luego te llevar\u00e9 donde la madre superiora.<\/p>\n\n\n\n<p>Mar\u00eda Cristina entr\u00f3 a la habitaci\u00f3n, una cama de hierro con s\u00e1banas blancas,&nbsp; armario color caf\u00e9, 4 cruces en cada pared,&nbsp; mesita de noche, un peque\u00f1o ba\u00f1o interno sin mucho lujo, el piso era un mosaico blanco y negro como tablero de ajedrez, hab\u00eda una ventana con vista al mar donde se pod\u00eda ver el ocaso, se tir\u00f3 en la cama, durmi\u00f3 un poco, im\u00e1genes del accidente llegaban, sangre, sirenas de ambulancias y carros de polic\u00eda, despert\u00f3 agitada y se coloc\u00f3 en posici\u00f3n sentada en la cama, con las manos en la cabeza, alguien toca la puerta.<\/p>\n\n\n\n<p>-Mar\u00eda Cristina, soy la hermana Esther.<\/p>\n\n\n\n<p>Mar\u00eda Cristina abre la puerta, la hermana le deja una t\u00fanica blanca usada pero limpia.<\/p>\n\n\n\n<p>-Ac\u00e1 te dejo tu h\u00e1bito, te esperamos en el altar para presentarte a la madre superiora.<\/p>\n\n\n\n<p>Mar\u00eda Cristina lo tomaba, no le dio las gracias y cerraba la puerta, se dio un ba\u00f1o , se coloc\u00f3 el h\u00e1bito, le quedaba algo suelto pero c\u00f3modo, sali\u00f3 de la habitaci\u00f3n, hab\u00eda una hermana cortando unas flores, se le ve\u00eda triste y haciendo el oficio por obligaci\u00f3n m\u00e1s que por devoci\u00f3n.<\/p>\n\n\n\n<p>-Disculpa, donde queda el altar.<\/p>\n\n\n\n<p>La hermana no responde, solo le hace se\u00f1a con la boca indicando derecho. Mar\u00eda Cristina camina hasta llegar a una puerta grande, antigua, con Cristo crucificado tallado, la abri\u00f3, la puerta hace un relinchido, hay unas hermanas orando al fondo, el ruido hace que miren hacia atr\u00e1s, todas la miran, silenciosamente Mar\u00eda Cristina se sienta en una butaca, una hermana se acerca a ella sonriendo.<\/p>\n\n\n\n<p>-Hola Mar\u00eda Cristina, acomp\u00e1\u00f1ame.<\/p>\n\n\n\n<p>Mari\u00e1 Cristina es llevada a una oficina. tocan.&nbsp;<\/p>\n\n\n\n<p>-Adelante &#8211; Dice una voz anciana.<\/p>\n\n\n\n<p>-Buenas tardes madre superiora, le presento a Mar\u00eda Cristina, nuestra nueva novicia.<\/p>\n\n\n\n<p>Era una oficina amplia , con una biblioteca al costado, al otro costado hab\u00eda una puerta que ten\u00eda un candado grande, Mar\u00eda Cristina la miro y le llegaron a su mente im\u00e1genes de sufrimiento y sangre.<\/p>\n\n\n\n<p>-Hola Mar\u00eda Cristina, \u00bfte pasa algo? Te damos la bienvenida al convento Santa&nbsp; Cruz de la Popa, este es el lugar que tu necesitas.<\/p>\n\n\n\n<p>Mar\u00eda Cristina not\u00f3 que la anciana no era sincera y que en su voz hab\u00eda algo oscuro, solo la miraba no dec\u00eda nada, ten\u00eda una postura defensiva.&nbsp;<\/p>\n\n\n\n<p>-Creo que debes tener hambre, ya casi es hora de almuerzo, hermana por favor ll\u00e9vela&nbsp; al comedor con las dem\u00e1s novicias.<\/p>\n\n\n\n<p>Mar\u00eda Cristina fue llevada al comedor, hab\u00edan 6 j\u00f3venes en dos mesas distintas, hab\u00eda comida en buf\u00e9t.&nbsp;<\/p>\n\n\n\n<p>-Tienes que servirte tu misma. &#8211; Dijo la hermana que estaba a su lado.<\/p>\n\n\n\n<p>Mar\u00eda Cristina tom\u00f3 carne, dos papas cocidas, ensalada de pepino y un vaso de agua de panela, se sent\u00f3 sola muy retirada del grupo, la hermana la deja y se despide.<\/p>\n\n\n\n<p>En una de las mesas una de las j\u00f3venes monjas estaba llorando inconsolablemente, alguien se le acerc\u00f3 a Mar\u00eda Cristina.<\/p>\n\n\n\n<p>-Hola, me llamo In\u00e9s, bienvenida a tu peor pesadilla.<\/p>\n\n\n\n<p>-No se de qu\u00e9 hablas &#8211; dice Mar\u00eda Cristina confundida.<\/p>\n\n\n\n<p>-Pronto lo sabr\u00e1s.<\/p>\n\n\n\n<p>La novicia se dirige donde la monja que lloraba y le coloca la mano en la espalda.<\/p>\n\n\n\n<p>-Ya pas\u00f3, no te preocupes no est\u00e1s sola.<\/p>\n\n\n\n<p>Despu\u00e9s de comer otra hermana lleg\u00f3 por Mar\u00eda Cristina y por dos novicias m\u00e1s.<\/p>\n\n\n\n<p>-Por favor seguirme, les voy a mostrar su \u00e1rea de trabajo.<\/p>\n\n\n\n<p>Son llevadas a una habitaci\u00f3n con olor a creolina, hab\u00edan unas canastas, muchas pepitas, pitas e im\u00e1genes de cristo y la virgen del Carmen.<\/p>\n\n\n\n<p>-Hermanas, ella es la hermana Rebeca y les va a ense\u00f1ar hacer escapularios, tenemos un pedido que debemos entregar el s\u00e1bado.<\/p>\n\n\n\n<p>La hermana Rebeca les mostr\u00f3 el oficio no era nada dif\u00edcil, solo met\u00edas unas bolitas en una pita hacer un nudo y sale, In\u00e9s entr\u00f3 se sienta y se coloca a hacer su trabajo, Mar\u00eda Cristina se le acerca.<\/p>\n\n\n\n<p>-\u00a1Oye! que tratabas de decirme con que ser\u00e1 mi peor pesadilla.<\/p>\n\n\n\n<p>-Que bonita cicatriz, me gusta \u00bfC\u00f3mo te la hiciste?<\/p>\n\n\n\n<p>-Responde \u00bfque tratas de decir?&nbsp;<\/p>\n\n\n\n<p>-Mira cara bonita, ac\u00e1 nada es lo que parece, me avisas si puedes dormir.<\/p>\n\n\n\n<p>Mar\u00eda Cristina se retira, se sienta en una mesa y se coloca a meter pepitas en una pita.&nbsp;<\/p>\n\n\n\n<p>11 pm, primera noche, Mar\u00eda Cristina estaba en su cama arropada mirando el techo, trataba de cerrar los ojos, se estaba quedando dormida, unos gritos la despertaron, sonidos de l\u00e1tigos, m\u00e1s gritos, llantos, m\u00e1s l\u00e1tigos, se levant\u00f3, abri\u00f3 la puerta, se asom\u00f3, de la nada es sorprendida, alguien le tapa la boca y la vuelve a meter a la habitaci\u00f3n.<\/p>\n\n\n\n<p>Continuar\u00e1\u2026..<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Larry Caballero 17 de agosto 1958,&nbsp; Chevrolet impala, modelo 56, color rojo, techo r\u00edgido,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":5685,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[33],"tags":[],"class_list":["post-5684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-los-seguidores-dicen"],"featured_image_urls":{"full":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/IMG_20221225_092026.jpg",898,991,false],"thumbnail":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/IMG_20221225_092026-150x150.jpg",150,150,true],"medium":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/IMG_20221225_092026-272x300.jpg",272,300,true],"medium_large":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/IMG_20221225_092026-768x848.jpg",640,707,true],"large":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/IMG_20221225_092026.jpg",640,706,false],"1536x1536":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/IMG_20221225_092026.jpg",898,991,false],"2048x2048":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/IMG_20221225_092026.jpg",898,991,false],"newsever-slider-full":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/IMG_20221225_092026-898x845.jpg",898,845,true],"newsever-featured":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/IMG_20221225_092026.jpg",898,991,false],"newsever-medium":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/IMG_20221225_092026-720x475.jpg",720,475,true]},"author_info":{"info":["Noticias La Primicia"]},"category_info":"<a href=\"https:\/\/laprimicianoticias.com\/index.php\/category\/los-seguidores-dicen\/\" rel=\"category tag\">Los seguidores dicen:<\/a>","tag_info":"Los seguidores dicen:","comment_count":"4","_links":{"self":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/5684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=5684"}],"version-history":[{"count":1,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/5684\/revisions"}],"predecessor-version":[{"id":5686,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/5684\/revisions\/5686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/media\/5685"}],"wp:attachment":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=5684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=5684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=5684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}