{"id":5595,"date":"2022-12-11T17:29:42","date_gmt":"2022-12-11T17:29:42","guid":{"rendered":"https:\/\/laprimicianoticias.com\/?p=5595"},"modified":"2022-12-11T17:29:43","modified_gmt":"2022-12-11T17:29:43","slug":"la-chica-del-piercing-en-la-nariz","status":"publish","type":"post","link":"https:\/\/laprimicianoticias.com\/index.php\/2022\/12\/11\/la-chica-del-piercing-en-la-nariz\/","title":{"rendered":"La Chica del piercing en la nariz"},"content":{"rendered":"\n<p>Trabajo mediocre en una ferreter\u00eda, mal pago, pero lo suficiente para sobrevivir. Solo los viernes mi v\u00e1lvula de alivio en el bar &#8220;Gato negro&#8221;, lo habitual 5 cervezas, caminar a casa, mirar el techo mientras pueda cerrar los ojos y pensar que se har\u00e1 el s\u00e1bado.\u00a0<\/p>\n\n\n\n<p>Viernes 15 de marzo, lo aburridamente normal en gato negro, dos tipos peor vestidos que yo, un misterioso hombre en la mesa de la esquina y 4 amigas ri\u00e9ndose haciendo caser\u00eda. Yo en la barra con mi tercera cerveza y mi plato de man\u00ed, viendo la TV, un v\u00eddeo que no ten\u00eda nada que ver con el vallenato que sonaba &gt;Sin medir distancias Diomedes D\u00edaz&lt;. Abriendo la puerta principal hace una entrada majestuosa ella, flaca, con caderas anchas, senos peque\u00f1o pero tentadores para verlos, pelo te\u00f1ido entre rojo y cobre, vestido ajustado negro, tatuajes en el cuello (dos tri\u00e1ngulos invertidos) y un piercing en la nariz que la hac\u00eda lucir desquiciada; sin duda alguna espl\u00e9ndida. Por extra\u00f1as razones llegaba sola y para m\u00ed suerte se sent\u00f3 a mi lado, pide media de&nbsp; aguardiente y un plato de lim\u00f3n picado, saca de su bolso brillante una caja de Malboro rojo y una mechera negra, los coloca en la barra de un golpe seco.&nbsp;<\/p>\n\n\n\n<p>Me mira sonr\u00ede y me pregunta;&nbsp;<\/p>\n\n\n\n<p>_Te gusta mi pelo?_ dijo mir\u00e1ndome fijamente.&nbsp;<\/p>\n\n\n\n<p>_Si_Respondi en un segundo _ y agregu\u00e9.&nbsp;<\/p>\n\n\n\n<p>_No solo es bonito, te queda perfecto ese largo.&nbsp;<\/p>\n\n\n\n<p>Ella sonr\u00ede y dice.&nbsp;<\/p>\n\n\n\n<p>_Hoy un cabron me dej\u00f3 metida, pero \u00e9l se lo pierde, la noche es joven y ac\u00e1 estoy con media de aguardiente.&nbsp;<\/p>\n\n\n\n<p>_Tienes raz\u00f3n la noche es joven y no vale la pena_ le habl\u00e9 con confianza.&nbsp;<\/p>\n\n\n\n<p>_Mi nombre es Camilo.&nbsp;<\/p>\n\n\n\n<p>_Un Gusto Camilo, Zoe, fumas?&nbsp;<\/p>\n\n\n\n<p>Yo hab\u00eda dejado el cigarrillo, pero no quise ser descort\u00e9s,&nbsp; ambos fumamos, ella me daba de su trago y yo ped\u00eda dos cervezas; as\u00ed fuimos hablando, bailamos merengue, salsa , vallenatos, para mi fortuna odiaba el reguet\u00f3n igual que yo.&nbsp;<\/p>\n\n\n\n<p>_Donde vives Camilo?_ pregunto ella, ya sentados tomando aire despu\u00e9s de unos pases de salsa.&nbsp;<\/p>\n\n\n\n<p>_Vivo a tres calles de ac\u00e1 , por la novena. Y tu?&nbsp;<\/p>\n\n\n\n<p>_Yo vivo al sur, por la entrada de la calle grande.&nbsp;<\/p>\n\n\n\n<p>Note en su brazo izquierdo cicatrices como de cortadas, quise preguntar, pero tal vez la situaci\u00f3n iba a ser inc\u00f3modo para ella, mejor despu\u00e9s me dije. Al rato despu\u00e9s de casi&nbsp; 2 horas de seguir con nuestra conversaci\u00f3n con inter\u00e9s mutuo, y ya bastante iniciados por el alcohol, me pregunte si volver\u00eda a verla, entonces me lanc\u00e9 a sus labios, no quer\u00eda quedarme con las ganas de besarla y que est\u00e1 fuera la \u00fanica noche, la \u00fanica oportunidad de hacerlo; Fui correspondido y el beso fue largo y muy caliente, entre los besos nos re\u00edamos, pensando en que bella coincidencia&nbsp; , todo eres sencillamente genial. Ya iban a cerrar, pagamos la cuenta y sin preguntar nada, ambos comprendimos las&nbsp; se\u00f1ales corporales,&nbsp; nos fuimos caminando hacia&nbsp; mi apartamento, entramos bes\u00e1ndonos como dos locos de remate, nos tiramos al sof\u00e1 nos quitamos la ropa con tanta facilidad, pase mis manos por su espalda y note m\u00e1s cicatrices, no le di importancia, bes\u00e9 sus peque\u00f1os senos, mientras ella me alborotada el pelo, la tire de espalda, me coloque el cond\u00f3n y&nbsp; penetr\u00e1ndola fuertemente escuch\u00e9 su grito de placer, pude ver sus cicatrices que la verdad le quedaban bien, su vagina era c\u00e1lida, suave, yo quer\u00eda que el acto durara m\u00e1s tiempo, pero era imposible contener mi eyaculaci\u00f3n, sus gemidos eran fuerte, no nos importa el ruido ni si lo vecinos escuchaba.&nbsp;<\/p>\n\n\n\n<p>_No quiero que te vengas en el cond\u00f3n, llega en mi culo. _dijo ella casi muerta de placer.&nbsp;<\/p>\n\n\n\n<p>Ya con el semen casi en la punta , saque mi pene , retire el cond\u00f3n y eyacule en sus nalgas redondas, la vista era perfecta y el momento glorioso. Me tir\u00e9 en su espalda, acariciando su pelo y bes\u00e1ndole el cuello, nos quedamos dormido por unos minutos, luego volvimos a coger en el ba\u00f1o Mientras nos dimos una ducha para ir a dormir, no fue necesario preguntar si se iba a quedar, todo lo comprendimos a la perfecci\u00f3n, era como un deja Vu, algo que ya hab\u00eda pasado.&nbsp;<\/p>\n\n\n\n<p>Por la ma\u00f1ana despert\u00e9 con algo de guayabo, ella est\u00e1 all\u00ed posando en mi cama desnuda, sin duda era la mujer m\u00e1s bella con lo que yo hab\u00eda estado, fui a la cocina, prepare caf\u00e9, ella me sorprendi\u00f3 d\u00e1ndome un abrazo por la espalda.&nbsp;<\/p>\n\n\n\n<p>_Buenos d\u00edas , dijo ella con voz complaciente.&nbsp;<\/p>\n\n\n\n<p>_Hola , no te quise despertar, te estoy preparando un caf\u00e9.&nbsp;<\/p>\n\n\n\n<p>_Me tengo que ir_dijo Zoe.&nbsp;<\/p>\n\n\n\n<p>_Entiendo, te volver a ver?&nbsp;<\/p>\n\n\n\n<p>_Viernes en Gato negro.&nbsp;<\/p>\n\n\n\n<p>Nos dimos un ba\u00f1o , se cambi\u00f3 y se march\u00f3, no quiso que yo la acompa\u00f1ar\u00e1, solo se march\u00f3 dando un beso en mi boca&gt;Nos vemos el viernes&lt;.&nbsp;<\/p>\n\n\n\n<p>Sagradamente todos los viernes hac\u00edamos lo mismo, yo le contaba mis cosas , mi trabajo aburrido, ella me cont\u00f3 lo que hacia, trabajaba como auxiliar de enfermer\u00eda, pero odiaba su trabajo, est\u00e1 ahorrando para salir del pa\u00eds y buscar mejor suerte, viv\u00eda con su mam\u00e1 y un padrastro alcoh\u00f3lico, all\u00ed fue donde me enter\u00e9 de la infancia maldita que tuvo. Fue violada por su padrastro a las 9 a\u00f1os, su mam\u00e1 la maltratada porque le dec\u00eda que todo era invento de ella y le pagaba con el cord\u00f3n de la plancha por todo el cuerpo, de all\u00ed sus cicatrices en la espalda, las cicatrices del brazo izquierdo eran&nbsp; hechas&nbsp; por ella misma, se las hac\u00eda con un exacto cada ves que su padrastro la violaba, 13 en total . Nadie le cre\u00eda, solo una t\u00eda que sospecha y fue quien la saco de ese infierno de hogar que ten\u00eda, Zoe juro alg\u00fan d\u00eda vengarse, crec\u00eda y se volvi\u00f3 rebelde, volvi\u00f3 a casa de su Madre para poder ver el final de ese desgraciado que ya era un anciano y que el alcohol lentamente lo estaba matando, pero ella nunca olvidaba y su venganza iba porque iba.<\/p>\n\n\n\n<p>Sal\u00ed de la ciudad por 3 meses, para ayudar en una sucursal de una ferreter\u00eda nueva, en ese tiempo no supe nada de Zoe, la extra\u00f1aba, extra\u00f1aba todo de ella, hablar, re\u00edr , hacer el amor como conejos, y me intrigaba saber c\u00f3mo iba las cosas en su hogar. Regrese , el viernes fui a Gato negro , y all\u00ed est\u00e1ba, pero no estaba sola, me acerqu\u00e9, estaba muy borracha, a duras penas me reconoci\u00f3, se&nbsp; lanzo sobre mi, me dio un beso y pego una cachetada.<\/p>\n\n\n\n<p>_Porque te fuiste sin avisarme_ dijo con la lengua medio trabada&nbsp;<\/p>\n\n\n\n<p>_Eres un puto cabron de Mierda como todos. .<\/p>\n\n\n\n<p>Tenia toda la raz\u00f3n , yo me fui sin decirle nada, la verdad me estaba enamorado de ella y no lo quer\u00eda aceptar, pens\u00e9 que irme sin avisar era lo mejor, pero la verdad fue peor, porque no dejaba de pensar el ella.<\/p>\n\n\n\n<p>El sujeto con qui\u00e9n estaba me hizo a\u00fan lado y me dijo<\/p>\n\n\n\n<p>_Broo vete ella est\u00e1 conmigo hoy, hoy es mi turno.<\/p>\n\n\n\n<p>Hablo como si ella fuera una puta por la que hab\u00eda que esperar para poder tenerla.<\/p>\n\n\n\n<p>_Que ella decida, Dije con voz fuerte y quit\u00e1ndole las manos de encima.<\/p>\n\n\n\n<p>_Zoe , v\u00e1monos de aqu\u00ed, te quiero explicar,&nbsp;<\/p>\n\n\n\n<p>_Noo , vete , eres una mierda,&nbsp; por eso no debo confiar en los hombres, solo quieren cogerme y se van.<\/p>\n\n\n\n<p>_Zoe te equivocas, vine por ti.<\/p>\n\n\n\n<p>El guardia se acerc\u00f3 .<\/p>\n\n\n\n<p>_Amigo si no se calman los tendr\u00e9 que sacar.<\/p>\n\n\n\n<p>_Vete_ dijo el acompa\u00f1ante empuj\u00e1ndome.<\/p>\n\n\n\n<p>Saque fuerzas y le di un pu\u00f1o que lo tire contra las mesas, al Guardia me saco con violencia, era un gorila de&nbsp; uno dos metros que nada pude hacer , me arrojo a la calle amenazando con traer a la polic\u00eda si volv\u00eda a&nbsp; entrar.<\/p>\n\n\n\n<p>Me qued\u00e9 afuera esperando que Zoe saliera, un rato despu\u00e9s la vi salir, casi no pod\u00eda caminar de la borrachera. Quise insistir, pero no , solo la dej\u00e9 marchar, vi como tomaron un taxi y mi mente se reventaba de pensar como iba a coger con ese acompa\u00f1ante nuevo,&nbsp; me fui al estanco de la esquina, compre una cerveza y fume un cigarro, no pod\u00eda creer lo que pasaba y lo cobarde que era,&nbsp; porque dej\u00e9 perder a Zoe,&nbsp; porque no me arriesgue, porque ese miedo de enamorarme, de decirlo , de luchar, me sent\u00eda miserable, perdedor, y ella est\u00e1 noche iba hacer penetrada por alguien que tal ves no vea lo que yo vi en ella, Ya todo se acabo, debo asumir mi acto de cobard\u00eda, camin\u00e9 hasta mi apartamento intentando no pensar m\u00e1s y solo dormir.<\/p>\n\n\n\n<p>Pase el s\u00e1bado encerrado, no quer\u00eda saber nada de nada, solo en mi cama , era una depresi\u00f3n, hice un resumen visual de mi vida y todo era fracas\u00f3, mediocridad, no era nada especial, pero fui tomando fuerza y decid\u00ed hacer algo bien por primera vez, y quer\u00eda luchar, as\u00ed que tome una hoja, un l\u00e1piz y comenc\u00e9 a escribir una carta para Zoe , sab\u00eda que la volver\u00eda a ver alg\u00fan viernes, en esa carta le contar\u00eda todo lo que sent\u00eda y que quer\u00eda una vida con ella. Pase el resto del s\u00e1bado escribiendo.<\/p>\n\n\n\n<p>El domingo temprano sal\u00ed a comprar leche donde el se\u00f1or Iv\u00e1n, y est\u00e1ba el peri\u00f3dico amarillista con la primicia.<\/p>\n\n\n\n<p>&#8220;Chica con piercing en la nariz mata a su padrastro de 13 cuchilladas y luego se suicida cort\u00e1ndose la garganta&#8221;.<\/p>\n\n\n\n<p>La gente est\u00e1 loca , que MIERDA de J\u00f3venes los de hoy en d\u00eda._ Dijo Don Iv\u00e1n.<\/p>\n\n\n\n<p>Por : Larry Caballero<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trabajo mediocre en una ferreter\u00eda, mal pago, pero lo suficiente para sobrevivir. Solo los viernes&#8230;<\/p>\n","protected":false},"author":1,"featured_media":5596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[33],"tags":[],"class_list":["post-5595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-los-seguidores-dicen"],"featured_image_urls":{"full":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/1670678762814.jpg",1080,1791,false],"thumbnail":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/1670678762814-150x150.jpg",150,150,true],"medium":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/1670678762814-181x300.jpg",181,300,true],"medium_large":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/1670678762814-768x1274.jpg",640,1062,true],"large":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/1670678762814-617x1024.jpg",617,1024,true],"1536x1536":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/1670678762814-926x1536.jpg",926,1536,true],"2048x2048":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/1670678762814.jpg",1080,1791,false],"newsever-slider-full":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/1670678762814-1080x845.jpg",1080,845,true],"newsever-featured":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/1670678762814-1024x1698.jpg",1024,1698,true],"newsever-medium":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2022\/12\/1670678762814-720x475.jpg",720,475,true]},"author_info":{"info":["Noticias La Primicia"]},"category_info":"<a href=\"https:\/\/laprimicianoticias.com\/index.php\/category\/los-seguidores-dicen\/\" rel=\"category tag\">Los seguidores dicen:<\/a>","tag_info":"Los seguidores dicen:","comment_count":"1","_links":{"self":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/5595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=5595"}],"version-history":[{"count":1,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/5595\/revisions"}],"predecessor-version":[{"id":5597,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/5595\/revisions\/5597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/media\/5596"}],"wp:attachment":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=5595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=5595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=5595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}