{"id":4125,"date":"2021-11-22T12:26:07","date_gmt":"2021-11-22T12:26:07","guid":{"rendered":"https:\/\/laprimicianoticias.com\/?p=4125"},"modified":"2021-11-22T12:28:05","modified_gmt":"2021-11-22T12:28:05","slug":"minsalud-recuerda-como-se-deben-desechar-los-tapabocas-de-forma-responsable","status":"publish","type":"post","link":"https:\/\/laprimicianoticias.com\/index.php\/2021\/11\/22\/minsalud-recuerda-como-se-deben-desechar-los-tapabocas-de-forma-responsable\/","title":{"rendered":"Minsalud recuerda c\u00f3mo se deben desechar los tapabocas de forma responsable"},"content":{"rendered":"\n<p>El Ministerio de Salud y Protecci\u00f3n Social recuerda que expidi\u00f3 el protocolo general de bioseguridad para el manejo de los residuos de tapabocas y guantes contenido en el numeral 3.1.7. Manejo de residuos, incluido en la Resoluci\u00f3n 777 de 2021.<\/p>\n\n\n\n<p>Jairo Hern\u00e1ndez, subdirector de Salud Ambiental del Ministerio, record\u00f3 que frente al aumento del uso de esto elementos es importante realizar un uso y desecho responsables de tapabocas, guantes y residuos para no tener afectaciones en la salud ambiental.<\/p>\n\n\n\n<p>&#8220;En el pa\u00eds y en el mundo, desde el inicio de la pandemia, se han utilizado millones de tapabocas desechables y muchos de ellos han acabado en las calles, v\u00edas p\u00fablicas, parques, r\u00edos o playas, poniendo en riesgo la salud de las personas, familias, comunidades y contaminando el ambiente, por lo tanto, no arroje o deseche los tapabocas en espacios p\u00fablicos&#8221;, explic\u00f3.<\/p>\n\n\n\n<p>Por esta raz\u00f3n, destac\u00f3 Hern\u00e1ndez, es importante que &#8220;se realice la separaci\u00f3n de estos residuos en doble bolsa de color negra que no debe ser abierta por el personal que realiza el reciclaje de oficio. Dichos residuos ser\u00e1n presentados al servicio p\u00fablico de aseo en los horarios establecidos y dando cumplimiento a las condiciones de presentaci\u00f3n de estos&#8221;.&nbsp;<\/p>\n\n\n\n<p><strong>Recomendaciones<\/strong><\/p>\n\n\n\n<p><strong>Antes de usarlo<\/strong>: Lavarse las manos, el tapabocas debe estar limpio.<\/p>\n\n\n\n<p><strong>Durante su uso<\/strong>: Manipular el tapabocas desde la cuerdas o tirillas de soporte y no desde la superficie de este, recuerde lavar las manos antes y luego de la manipulaci\u00f3n del tapabocas, use tapabocas siempre, especialmente cuando se encuentre con otras personas en un recinto cerrado.<\/p>\n\n\n\n<p><strong>Despu\u00e9s de su uso<\/strong>: L\u00e1vese las manos luego de retirar el tapabocas; al retirarse el tapabocas si es desechable, depos\u00edtelo en doble bolsa negra en una caneca destinada para la disposici\u00f3n de estos; en caso de ser reutilizable, l\u00e1velo con agua y jab\u00f3n una vez se lo retire. Por ning\u00fan motivo los tapabocas deben ser botados o abandonados.<\/p>\n\n\n\n<p>Fuente: Minsalud<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Salud y Protecci\u00f3n Social recuerda que expidi\u00f3 el protocolo general de bioseguridad&#8230;<\/p>\n","protected":false},"author":1,"featured_media":4126,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[27,32],"tags":[],"class_list":["post-4125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-primicia"],"featured_image_urls":{"full":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/11\/Tapabocas.jpeg",704,318,false],"thumbnail":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/11\/Tapabocas-150x150.jpeg",150,150,true],"medium":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/11\/Tapabocas-300x136.jpeg",300,136,true],"medium_large":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/11\/Tapabocas.jpeg",640,289,false],"large":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/11\/Tapabocas.jpeg",640,289,false],"1536x1536":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/11\/Tapabocas.jpeg",704,318,false],"2048x2048":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/11\/Tapabocas.jpeg",704,318,false],"newsever-slider-full":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/11\/Tapabocas.jpeg",704,318,false],"newsever-featured":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/11\/Tapabocas.jpeg",704,318,false],"newsever-medium":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/11\/Tapabocas.jpeg",704,318,false]},"author_info":{"info":["Noticias La Primicia"]},"category_info":"<a href=\"https:\/\/laprimicianoticias.com\/index.php\/category\/nacionales\/\" rel=\"category tag\">Nacionales<\/a> <a href=\"https:\/\/laprimicianoticias.com\/index.php\/category\/primicia\/\" rel=\"category tag\">Primicia<\/a>","tag_info":"Primicia","comment_count":"0","_links":{"self":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/4125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=4125"}],"version-history":[{"count":2,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/4125\/revisions"}],"predecessor-version":[{"id":4128,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/4125\/revisions\/4128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/media\/4126"}],"wp:attachment":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=4125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=4125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=4125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}