{"id":3080,"date":"2021-06-16T11:54:59","date_gmt":"2021-06-16T11:54:59","guid":{"rendered":"https:\/\/laprimicianoticias.com\/?p=3080"},"modified":"2021-06-16T11:55:01","modified_gmt":"2021-06-16T11:55:01","slug":"las-tecnicas-que-bill-gates-usa-para-comprender-y-no-olvidar-sus-lecturas","status":"publish","type":"post","link":"https:\/\/laprimicianoticias.com\/index.php\/2021\/06\/16\/las-tecnicas-que-bill-gates-usa-para-comprender-y-no-olvidar-sus-lecturas\/","title":{"rendered":"Las t\u00e9cnicas que Bill Gates usa para comprender y no olvidar sus lecturas"},"content":{"rendered":"\n<p>Adem\u00e1s de ser famoso por su riqueza, los pron\u00f3sticos futuristas, la filantrop\u00eda, sus campa\u00f1as ambientales y por supuesto por ser el cofundador de Microsoft, Bill Gates tambi\u00e9n se ha distinguido por recomendar libros. Este hombre anualmente alcanza a leer unos 50 libros. \u00bfPero c\u00f3mo hace para comprender y recordar todo lo que lee? El multimillonario a trav\u00e9s de una serie de reportajes en Quartz\u00a0revel\u00f3 algunas de las t\u00e9cnicas de lectura que aplica.<\/p>\n\n\n\n<p>Lo primero que hace Gates es tomar apuntes en los m\u00e1rgenes de los libros, especialmente en aquellos que no tratan temas de ficci\u00f3n. As\u00ed lo explica: <em>Tomar notas me asegura que estoy esforz\u00e1ndome en entender lo que leo.<\/em><\/p>\n\n\n\n<p>Una de sus normas personales es no empezar a leer libros\u00a0que cree no poder completar y, a los que decide leer, dedicar al menos un tiempo de lectura de una hora. El magnate considera que un libro no debe abrirse tan solo diez minutos para luego continuar con otra actividad, como si se tratara de un art\u00edculo de revista o un v\u00eddeo de YouTube.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"How Bill Gates reads books\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/eTFy8RnUkoU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Para tener claros los conceptos acerca de sus lecturas, Gates siempre busca ampliar el marco de conocimiento m\u00e1s all\u00e1 del contenido ofrecido por un solo libro. Esto dijo al respecto: &#8220;Si quieres aprender sobre ciencia, lee la historia de los cient\u00edficos, de cuando estaban confundidos y de las herramientas o ideas que les permitieron progresar. De esta forma obtienes la cronolog\u00eda, el mapa o las ramas de la ciencia de lo que se sabe y lo que no se sabe. El aprendizaje incremental es mucho m\u00e1s f\u00e1cil de retener&#8221;.<\/p>\n\n\n\n<p>El empresario reconoce que apartarse del tema por el cual te estabas interesando puede resultar \u201cmuy desalentador\u201d, pero agrega que, una vez consigues una visi\u00f3n general del contenido, todas las partes comienzan a encajar: &#8220;<em>Es divertido decir: \u00bfy esto no contradice algo que ya sab\u00eda antes? Mejor lo busco y lo descubro por mi cuenta. Realmente te molesta cuando lees cosas y hay cierta inconsistencia<\/em>&#8220;.<\/p>\n\n\n\n<p>Seg\u00fan Bill Gates, este grado de conocimiento es comparable con pretender que un jugador de ajedrez memorice la posici\u00f3n de cada una de las piezas puestas al azar en el tablero de juego. El ajedrecista es incapaz de captar esa informaci\u00f3n debido a que no existe un modo l\u00f3gico de llegar a esas posiciones llevando a cabo un juego de forma normal. Visualiza lo que otras personas no pueden visualizar.<\/p>\n\n\n\n<p>V\u00eda @GrandesMedios<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s de ser famoso por su riqueza, los pron\u00f3sticos futuristas, la filantrop\u00eda, sus campa\u00f1as ambientales&#8230;<\/p>\n","protected":false},"author":1,"featured_media":3081,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-3080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"featured_image_urls":{"full":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/06\/Las-tecnicas-que-Bill-Gates-usa-para-comprender-y-no-olvidar-todas-sus-lecturas.jpg",696,432,false],"thumbnail":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/06\/Las-tecnicas-que-Bill-Gates-usa-para-comprender-y-no-olvidar-todas-sus-lecturas-150x150.jpg",150,150,true],"medium":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/06\/Las-tecnicas-que-Bill-Gates-usa-para-comprender-y-no-olvidar-todas-sus-lecturas-300x186.jpg",300,186,true],"medium_large":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/06\/Las-tecnicas-que-Bill-Gates-usa-para-comprender-y-no-olvidar-todas-sus-lecturas.jpg",640,397,false],"large":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/06\/Las-tecnicas-que-Bill-Gates-usa-para-comprender-y-no-olvidar-todas-sus-lecturas.jpg",640,397,false],"1536x1536":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/06\/Las-tecnicas-que-Bill-Gates-usa-para-comprender-y-no-olvidar-todas-sus-lecturas.jpg",696,432,false],"2048x2048":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/06\/Las-tecnicas-que-Bill-Gates-usa-para-comprender-y-no-olvidar-todas-sus-lecturas.jpg",696,432,false],"newsever-slider-full":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/06\/Las-tecnicas-que-Bill-Gates-usa-para-comprender-y-no-olvidar-todas-sus-lecturas.jpg",696,432,false],"newsever-featured":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/06\/Las-tecnicas-que-Bill-Gates-usa-para-comprender-y-no-olvidar-todas-sus-lecturas.jpg",696,432,false],"newsever-medium":["https:\/\/laprimicianoticias.com\/wp-content\/uploads\/2021\/06\/Las-tecnicas-que-Bill-Gates-usa-para-comprender-y-no-olvidar-todas-sus-lecturas.jpg",696,432,false]},"author_info":{"info":["Noticias La Primicia"]},"category_info":"<a href=\"https:\/\/laprimicianoticias.com\/index.php\/category\/internacionales\/\" rel=\"category tag\">Internacionales<\/a>","tag_info":"Internacionales","comment_count":"0","_links":{"self":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/3080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=3080"}],"version-history":[{"count":1,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/3080\/revisions"}],"predecessor-version":[{"id":3082,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/3080\/revisions\/3082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/media\/3081"}],"wp:attachment":[{"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=3080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=3080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laprimicianoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=3080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}